{"id":1360,"count":28,"description":"","link":"https:\/\/evvtoltechnation.com\/zh\/%e7%b1%bb%e5%88%ab\/%e6%b1%bd%e8%bd%a6%e8%81%8c%e4%b8%9a%e6%96%b0%e9%97%bb\/","name":"\u6c7d\u8f66\u804c\u4e1a\u65b0\u95fb","slug":"%e6%b1%bd%e8%bd%a6%e8%81%8c%e4%b8%9a%e6%96%b0%e9%97%bb","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/evvtoltechnation.com\/zh\/wp-json\/wp\/v2\/categories\/1360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evvtoltechnation.com\/zh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/evvtoltechnation.com\/zh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/evvtoltechnation.com\/zh\/wp-json\/wp\/v2\/posts?categories=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}